{"id":1085,"date":"2024-09-02T14:41:46","date_gmt":"2024-09-02T14:41:46","guid":{"rendered":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/?p=1085"},"modified":"2020-08-16T21:06:37","modified_gmt":"2020-08-16T21:06:37","slug":"this-florida-city-is-the-best-place-to-retire-in-the-u-s-according-to-experts","status":"publish","type":"post","link":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/this-florida-city-is-the-best-place-to-retire-in-the-u-s-according-to-experts\/","title":{"rendered":"This Florida City Is the Best Place to Retire in the U.S., According to Experts"},"content":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1597515494202{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597515459818{padding-top: 0px !important;}&#8221;][vc_column_text]<\/p>\n<div class=\"styled-subtitle\"><span style=\"color: #1c2e3d;\">Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident!<\/span><\/div>\n<p>[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 40px;\"><\/div>[vc_column_text]Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia sequuntur magni dolores eos qui ratione voluptatem sequi nesciunt.[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 50px;\"><\/div><div style='border-color: #e7efef; color: #5f727f; '  class=\"gem-quote gem-quote-style-default gem-quote-no-paddings custom-color-blockqute-mark-added\" ><blockquote style='color: #5f727f ; border-color: #e7efef ' >&#8230;Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua!<\/blockquote><span style=color:#eff5f5;  class=\"custom-color-blockqute-mark\">&#xe60c;<\/span><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 40px;\"><\/div>[vc_column_text]Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore et quasi architecto vitae dicta sunt explicabo.[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 33px;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_end\">\ufeff<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1597515839371{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597515736922{padding-top: 0px !important;}&#8221;]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 25px;\"><\/div><div class=\"lazy-loading\" data-ll-item-delay=\"0\"><div class=\"gem-textbox  lazy-loading-item\"  data-ll-effect=\"move-up\" ><div class=\"gem-textbox-inner\" style=\"border: 1px solid #dfe5e8;\"><div class=\"gem-textbox-content\" style=\"background-position: center top;padding-top: 8px;padding-bottom: 21px;\"><div class=\"gem-dropcap gem-dropcap-shape-circle gem-dropcap-style-medium\"><span class=\"gem-dropcap-letter\" style=\"color: #ffffff;background-color: #26c6da;\">1<\/span><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: -45px;\"><\/div>[vc_column_text]<\/p>\n<div class=\"styled-subtitle\"><span style=\"color: #26c6da;\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod <\/span><\/div>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: -24px;\"><\/div><div class=\"lazy-loading\" data-ll-item-delay=\"0\"><div class=\"gem-textbox  lazy-loading-item\"  data-ll-effect=\"move-up\" ><div class=\"gem-textbox-inner\" style=\"border: 1px solid #dfe5e8;\"><div class=\"gem-textbox-content\" style=\"background-position: center top;padding-top: 8px;padding-bottom: 21px;\"><div class=\"gem-dropcap gem-dropcap-shape-circle gem-dropcap-style-medium\"><span class=\"gem-dropcap-letter\" style=\"color: #ffffff;background-color: #81d098;\">2<\/span><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: -45px;\"><\/div>[vc_column_text]<\/p>\n<div class=\"styled-subtitle\"><span style=\"color: #81d098;\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod <\/span><\/div>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: -25px;\"><\/div><div class=\"lazy-loading\" data-ll-item-delay=\"0\"><div class=\"gem-textbox  lazy-loading-item\"  data-ll-effect=\"move-up\" ><div class=\"gem-textbox-inner\" style=\"border: 1px solid #dfe5e8;\"><div class=\"gem-textbox-content\" style=\"background-position: center top;padding-top: 8px;padding-bottom: 21px;\"><div class=\"gem-dropcap gem-dropcap-shape-circle gem-dropcap-style-medium\"><span class=\"gem-dropcap-letter\" style=\"color: #ffffff;background-color: #6c97e8;\">3<\/span><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: -45px;\"><\/div>[vc_column_text]<\/p>\n<div class=\"styled-subtitle\"><span style=\"color: #6c97e8;\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod <\/span><\/div>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1597515847657{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597515851844{padding-top: 0px !important;}&#8221;]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 30px;\"><\/div>[vc_column_text]Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur magni dolores eos qui ratione voluptatem sequi nesciunt. Neque porro quisquam est, qui dolorem ipsum quia dolor sit amet, consectetur, adipisci velit, sed quia non numquam eius modi tempora incidunt ut labore et dolore magnam aliquam quaerat voluptatem. Lorem ipsum dolor amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit invelit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa ab illo inventore veritatis et quasi beatae vitae dicta sunt explicabo.[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 92px;\"><\/div><div class=\"preloader save-space\"><div class=\"preloader-spin\"><\/div><\/div><div class=\"gallery-preloader-wrapper\"> <div class=\"row\" style=\"margin-top: -21px\"> <div class=\"gem-gallery-grid col-lg-12 col-md-12 col-sm-12 gallery-style-justified hover-default loading-animation item-animation-move-up columns-3 gaps-margin \" data-hover=\"default\"> <ul style=\"margin-left: -21px; margin-right: -21px;\" class=\"gallery-set clearfix\" data-max-row-height=\"380\"> <li style=\"padding: 21px\" class=\"gallery-item col-lg-4 col-md-4 col-sm-6 col-xs-6 item-animations-not-inited post-1085 post type-post status-publish format-audio category-adventure tag-agency tag-design tag-fly tag-holiday tag-lifestyle tag-media tag-nature tag-news tag-people tag-photo tag-sea tag-sun tag-travel post_format-post-format-audio\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/3-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/3-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/3-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/3-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/3-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"3\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/3.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a5730d2296f6\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/3.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-4 col-md-4 col-sm-6 col-xs-6 item-animations-not-inited post-1085 post type-post status-publish format-audio category-adventure tag-agency tag-design tag-fly tag-holiday tag-lifestyle tag-media tag-nature tag-news tag-people tag-photo tag-sea tag-sun tag-travel post_format-post-format-audio\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/8-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/8-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/8-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/8-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/8-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"8\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/8.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a5730d2296f6\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/8.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-4 col-md-4 col-sm-6 col-xs-6 item-animations-not-inited post-1085 post type-post status-publish format-audio category-adventure tag-agency tag-design tag-fly tag-holiday tag-lifestyle tag-media tag-nature tag-news tag-people tag-photo tag-sea tag-sun tag-travel post_format-post-format-audio\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/7-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/7-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/7-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"7\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/7.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a5730d2296f6\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/7.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-4 col-md-4 col-sm-6 col-xs-6 item-animations-not-inited post-1085 post type-post status-publish format-audio category-adventure tag-agency tag-design tag-fly tag-holiday tag-lifestyle tag-media tag-nature tag-news tag-people tag-photo tag-sea tag-sun tag-travel post_format-post-format-audio\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/6-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/6-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/6-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/6-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/6-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"6\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/6.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a5730d2296f6\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/6.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-4 col-md-4 col-sm-6 col-xs-6 item-animations-not-inited post-1085 post type-post status-publish format-audio category-adventure tag-agency tag-design tag-fly tag-holiday tag-lifestyle tag-media tag-nature tag-news tag-people tag-photo tag-sea tag-sun tag-travel post_format-post-format-audio\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/5-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/5-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/5-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/5-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/5-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"5\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/5.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a5730d2296f6\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/5.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-4 col-md-4 col-sm-6 col-xs-6 item-animations-not-inited post-1085 post type-post status-publish format-audio category-adventure tag-agency tag-design tag-fly tag-holiday tag-lifestyle tag-media tag-nature tag-news tag-people tag-photo tag-sea tag-sun tag-travel post_format-post-format-audio\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/4-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/4-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/4-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/4-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/4-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"4\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/4.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a5730d2296f6\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-content\/uploads\/2019\/09\/4.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <\/ul> <\/div> <\/div> <\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 45px;\"><\/div>[vc_column_text]Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia sequuntur magni dolores eos qui ratione voluptatem sequi nesciunt.[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 10px;\"><\/div>[vc_column_text]Neque porro quisquam est, qui dolorem ipsum quia dolor sit amet, consectetur, adipisci velit, sed quia non numquam. Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit, sed quia consequuntur magni dolores eos qui ratione voluptatem sequi nesciunt. Neque porro quisquam est, qui dolorem ipsum quia dolor sit amet, consectetur, adipisci velit, sed quia non numquam eius modi tempora incidunt ut labore et dolore magnam aliquam quaerat voluptatem.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1597515494202{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1597515459818{padding-top: 0px !important;}&#8221;][vc_column_text] Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":[],"categories":[18],"tags":[15,10,16,4,12,13,5,14,11,6,7,8,9],"_links":{"self":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/posts\/1085"}],"collection":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/comments?post=1085"}],"version-history":[{"count":9,"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/posts\/1085\/revisions"}],"predecessor-version":[{"id":2479,"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/posts\/1085\/revisions\/2479"}],"wp:attachment":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/media?parent=1085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/categories?post=1085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/trip-blog-light\/wp-json\/wp\/v2\/tags?post=1085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}