{"id":80,"date":"2019-01-10T12:30:20","date_gmt":"2019-01-10T12:30:20","guid":{"rendered":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/homepage-2\/"},"modified":"2021-11-12T07:58:54","modified_gmt":"2021-11-12T07:58:54","slug":"portfolios-grid","status":"publish","type":"page","link":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolio\/portfolios-grid\/","title":{"rendered":"My Portfolios"},"content":{"rendered":"<p>[vc_row][vc_column]<div class=\"preloader save-space\"><div class=\"preloader-spin\"><\/div><\/div> <div class=\"portfolio-preloader-wrapper\"> <div class=\"portfolio portfolio-grid no-padding portfolio-pagination-scroll portfolio-style-justified background-style-white title-style-dark hover-vertical-sliding title-on-page caption-position-right loading-animation item-animation-flip columns-3 next-page-preloading filters-preloading\" data-portfolio-uid=\"8066f98\" data-current-page=\"1\" data-per-page=\"12\" data-next-page=\"0\" data-pages-count=\"1\" data-hover=\"vertical-sliding\"> <div class=\"portfilio-top-panel\" > <div class=\"portfilio-top-panel-row\"> <div class=\"portfilio-top-panel-left\"> <div class=\"portfolio-filters\"> <a href=\"#\" data-filter=\"*\" class=\"active all title-h6\"><i class=\"gem-print-icon gem-icon-pack-thegem-icons gem-icon-portfolio-show-all \"><\/i> <span class=\"light\">All<\/span><\/a> <a href=\"#\" data-filter=\".creative-web-project\" class=\"title-h6\"><span class=\"light\">Creative Web Project<\/span><\/a> <a href=\"#\" data-filter=\".minimalism\" class=\"title-h6\"><span class=\"light\">Minimalism<\/span><\/a> <a href=\"#\" data-filter=\".photography\" class=\"title-h6\"><span class=\"light\">Photography<\/span><\/a> <\/div> <div class=\"portfolio-filters-resp\"> <button class=\"menu-toggle dl-trigger\">Portfolio filters <span class=\"menu-line-1\"><\/span><span class=\"menu-line-2\"><\/span><span class=\"menu-line-3\"><\/span><\/button> <ul class=\"dl-menu\"> <li><a href=\"#\" data-filter=\"*\">All<\/a><\/li> <li><a href=\"#\" data-filter=\".creative-web-project\">Creative Web Project<\/a> <\/li> <li><a href=\"#\" data-filter=\".minimalism\">Minimalism<\/a> <\/li> <li><a href=\"#\" data-filter=\".photography\">Photography<\/a> <\/li> <\/ul> <\/div> <\/div> <div class=\"portfilio-top-panel-right\"> <div class=\"portfolio-sorting title-h6\"> <div class=\"orderby light\"> <label for=\"\" data-value=\"date\">Date<\/label> <a href=\"javascript:void(0);\" class=\"sorting-switcher\" data-current=\"date\"><\/a> <label for=\"\" data-value=\"name\">Name<\/label> <\/div> <div class=\"portfolio-sorting-sep\"><\/div> <div class=\"order light\"> <label for=\"\" data-value=\"DESC\">Desc<\/label> <a href=\"javascript:void(0);\" class=\"sorting-switcher\" data-current=\"DESC\"><\/a> <label for=\"\" data-value=\"ASC\">Asc<\/label> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-row-outer \"> <div class=\"row portfolio-row\" style=\"margin: -20px;\"> <div class=\"portfolio-set clearfix\" data-max-row-height=\"380\"> <div class=\"portfolio-item photography col-md-4 col-xs-4 item-animations-not-inited post-336 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562604\"> <div class=\"wrap clearfix\"> <div class=\"image post-336 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-1-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-1-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-1-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Clean Mockup Showcase\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/clean-mockup-showcase-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-1.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon outer-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-336 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Clean Mockup Showcase <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Easily Enable Gallery Slider<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"photography\">Photography<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-336\" title=\"Like this\"><span class=\"zilla-likes-count\">7<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item creative-web-project col-md-4 col-xs-4 item-animations-not-inited post-338 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562546\"> <div class=\"wrap clearfix\"> <div class=\"image post-338 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/7-2-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/7-2-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/7-2-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/7-2-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/7-2-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Minimalism\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/minimalism\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"\/\/player.vimeo.com\/video\/148111448?autoplay=1\" target=\"_self\" class=\"icon vimeo \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon inner-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-338 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Minimalism <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Elegant grid template with info sidebar<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"creative-web-project\">Creative Web Project<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-338\" title=\"Like this\"><span class=\"zilla-likes-count\">13<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item minimalism col-md-4 col-xs-4 item-animations-not-inited post-339 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562505\"> <div class=\"wrap clearfix\"> <div class=\"image post-339 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/3-3-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/3-3-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/3-3-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/3-3-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/3-3-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"New Ui Kit\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/3-3.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/new-ui-kit-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"\/\/www.youtube.com\/embed\/V2BBhqdQCXY?autoplay=1\" target=\"_self\" class=\"icon youtube \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-339 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> New Ui Kit <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Extended template for multi-purpose projects<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"minimalism\">Minimalism<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-339\" title=\"Like this\"><span class=\"zilla-likes-count\">9<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item photography col-md-4 col-xs-4 item-animations-not-inited post-340 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562431\"> <div class=\"wrap clearfix\"> <div class=\"image post-340 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/14-1-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/14-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/14-1-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/14-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/14-1-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Trendy Layout\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/trendy-layout-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/14-1.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon inner-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-340 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Trendy Layout <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Creative portfolio page for creative brains<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"photography\">Photography<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-340\" title=\"Like this\"><span class=\"zilla-likes-count\">3<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item creative-web-project col-md-4 col-xs-4 item-animations-not-inited post-341 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562407\"> <div class=\"wrap clearfix\"> <div class=\"image post-341 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/9-1-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/9-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/9-1-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/9-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/9-1-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Consulting\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/consulting\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/9-1.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon outer-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-341 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Consulting <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Easily Enable Gallery Slider<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"creative-web-project\">Creative Web Project<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-341\" title=\"Like this\"><span class=\"zilla-likes-count\">5<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item photography col-md-4 col-xs-4 item-animations-not-inited post-342 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562336\"> <div class=\"wrap clearfix\"> <div class=\"image post-342 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Photo Project\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/photo-project-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"\/\/player.vimeo.com\/video\/148111448?autoplay=1\" target=\"_self\" class=\"icon vimeo \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon inner-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-342 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Photo Project <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Elegant grid template with info sidebar<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"photography\">Photography<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-342\" title=\"Like this\"><span class=\"zilla-likes-count\">2<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item creative-web-project col-md-4 col-xs-4 item-animations-not-inited post-343 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562296\"> <div class=\"wrap clearfix\"> <div class=\"image post-343 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/27-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/27-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/27-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/27-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/27-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Architecture &#038; Interior\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/27.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/architecture-interior-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"\/\/www.youtube.com\/embed\/V2BBhqdQCXY?autoplay=1\" target=\"_self\" class=\"icon youtube \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-343 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Architecture &#038; Interior <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Extended template for multi-purpose projects<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"creative-web-project\">Creative Web Project<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-343\" title=\"Like this\"><span class=\"zilla-likes-count\">2<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item minimalism photography col-md-4 col-xs-4 item-animations-not-inited post-344 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562182\"> <div class=\"wrap clearfix\"> <div class=\"image post-344 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/6-2-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/6-2-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/6-2-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/6-2-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/6-2-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Rreal Estate 02\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/rreal-estate-02-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/6-2.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon inner-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-344 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Rreal Estate 02 <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Creative portfolio page for creative brains<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"minimalism\">Minimalism<\/a><span class=\"sep\"><\/span> <a data-slug=\"photography\">Photography<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-344\" title=\"Like this\"><span class=\"zilla-likes-count\">2<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item minimalism photography col-md-4 col-xs-4 item-animations-not-inited post-345 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562164\"> <div class=\"wrap clearfix\"> <div class=\"image post-345 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/13-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/13-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/13-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/13-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/13-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Creative Photography\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/creative-photography\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/13.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon outer-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-345 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Creative Photography <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Easily Enable Gallery Slider<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"minimalism\">Minimalism<\/a><span class=\"sep\"><\/span> <a data-slug=\"photography\">Photography<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-345\" title=\"Like this\"><span class=\"zilla-likes-count\">2<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item photography col-md-4 col-xs-4 item-animations-not-inited post-347 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562075\"> <div class=\"wrap clearfix\"> <div class=\"image post-347 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/8-2-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/8-2-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/8-2-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/8-2-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/8-2-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Photography Light\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/photography-light-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"\/\/player.vimeo.com\/video\/148111448?autoplay=1\" target=\"_self\" class=\"icon vimeo \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon inner-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-347 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Photography Light <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Elegant grid template with info sidebar<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"photography\">Photography<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-347\" title=\"Like this\"><span class=\"zilla-likes-count\">1<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item minimalism col-md-4 col-xs-4 item-animations-not-inited post-348 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547562058\"> <div class=\"wrap clearfix\"> <div class=\"image post-348 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-1-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-1-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-1-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-1-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Clean Minimalism\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/10-1.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/clean-minimalism-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"\/\/www.youtube.com\/embed\/V2BBhqdQCXY?autoplay=1\" target=\"_self\" class=\"icon youtube \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-348 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Clean Minimalism <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Extended template for multi-purpose projects<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"minimalism\">Minimalism<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-348\" title=\"Like this\"><span class=\"zilla-likes-count\">4<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <div class=\"portfolio-item creative-web-project col-md-4 col-xs-4 item-animations-not-inited post-349 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 20px;\" data-default-sort=\"0\" data-sort-date=\"1547561965\"> <div class=\"wrap clearfix\"> <div class=\"image post-349 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-4-thegem-portfolio-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-4-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-4-thegem-portfolio-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-4-thegem-portfolio-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-4-thegem-portfolio-justified.jpg\" width=\"844\" height=\"767\" class=\"attachment-thegem-portfolio-justified\" alt=\"Web Project\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/pf\/web-project-2\/\" target=\"_self\" class=\"icon self-link \"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-content\/uploads\/2019\/01\/1-4.jpg\" target=\"_self\" class=\"icon full-image fancy\"><i class=\"default\"><\/i><\/a> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/portfolios\/\" target=\"_self\" class=\"icon inner-link \"><i class=\"default\"><\/i><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-349 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"background-color: #2a2d3d; border-bottom-color: #2a2d3d;\"> <div class=\"title\" style=\"color: #ffffff\"> Web Project <\/div> <div class=\"caption-separator\" style=\"background-color: #00bcd4\"><\/div> <div class=\"subtitle\" style=\"color: #99a9b5\"><p>Creative portfolio page for creative brains<\/p>\n<\/div> <div class=\"info\"> 15 January, 2019 in&nbsp; <a data-slug=\"creative-web-project\">Creative Web Project<\/a> <\/div> <div class=\"portfolio-likes\"><i class=\"default\"><\/i><a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-349\" title=\"Like this\"><span class=\"zilla-likes-count\">2<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <div class=\"portfolio-item-size-container\"> <div class=\"portfolio-item col-md-4 col-xs-4 item-animations-not-inited post-349 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 0 20px !important;\"> <\/div> <\/div> <\/div><!-- .row--> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":353,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/pages\/80"}],"collection":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":19,"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":95,"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/pages\/80\/revisions\/95"}],"up":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/pages\/353"}],"wp:attachment":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/portfolio-dark\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}