{"id":826,"date":"2018-10-26T14:18:02","date_gmt":"2018-10-26T14:18:02","guid":{"rendered":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/?p=826"},"modified":"2019-04-22T11:09:38","modified_gmt":"2019-04-22T11:09:38","slug":"beauty-post-4","status":"publish","type":"post","link":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/beauty-post-4\/","title":{"rendered":"Beauty Post"},"content":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1547452732428{margin-bottom: 0px !important;}&#8221;][vc_column offset=&#8221;vc_col-md-6&#8243;]<div class=\"centered-box gem-image-centered-box\"><div class=\"gem-image gem-wrapbox gem-wrapbox-style-default gem-wrapbox-position-centered lazy-loading\"  style=\"\"><div class=\"gem-wrapbox-inner  lazy-loading-item\"  data-ll-effect=\"move-up\"><a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/1-9.jpg\" class=\"fancybox\"><img class=\"gem-wrapbox-element img-responsive\" src=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/1-9.jpg\" alt=\"\"\/><\/a><\/div><\/div><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 50px;\"><\/div>[\/vc_column][vc_column offset=&#8221;vc_col-md-6&#8243;][vc_column_text css=&#8221;.vc_custom_1547452775831{margin-top: -8px !important;}&#8221;]<\/p>\n<div class=\"title-h4\">Lorem ipsum dolor sit amet<\/div>\n<p>[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 30px;\"><\/div>[vc_column_text]Lorem ipsum dolor sit amet, consectetur adi pisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis exercitation ullamco laboris nisiut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo.[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 32px;\"><\/div><div class=\"gem-list lazy-loading gem-list-type-disc-style-1 gem-list-color-8\" ><ul>\n<li>Lorem ipsum dolor sit amet, consectetur adi pisicing elit<\/li>\n<li>Sed do eiusmod tempor incididunt ut labore et dolore magna aliqua<\/li>\n<li>Ut enim ad minim veniam, quis exercitation ullamco laboris nisiut aliquip<\/li>\n<li>Duis aute irure dolor in reprehenderit in voluptate velit esse<\/li>\n<\/ul>\n<\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 32px;\"><\/div>[vc_column_text]Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum. Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium doloremque laudantium, totam rem aperiam, eaque ipsa quae ab illo inventore veritatis et quasi architecto beatae vitae dicta sunt explicabo.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1547452732428{margin-bottom: 0px !important;}&#8221;][vc_column]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 40px;\"><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1547452732428{margin-bottom: 0px !important;}&#8221;][vc_column offset=&#8221;vc_col-md-6&#8243;][vc_column_text css=&#8221;.vc_custom_1547453380590{margin-top: -8px !important;}&#8221;]Lorem ipsum dolor sit amet, consectetur adi pisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis exercitation ullamco laboris nisiut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur.\u00a0Sed ut perspiciatis unde omnis iste natus error sit voluptatem accusantium.[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 48px;\"><\/div><div style='background-color: #f9f6f5; '  class=\"gem-quote gem-quote-style-1 gem-quote-no-paddings custom-color-blockqute-mark-added\" ><blockquote  ><\/p>\n<div class=\"title-h5\"><span class=\"light\">&#8230;Lorem Ipsum proin gravida nibh vel velit auctor aliquet Aenean lorem quis bibendum auctor, nisi elit consequat ipsum, nec sagittis sem!<\/span><\/div>\n<p><\/blockquote><span style=color:#efb0b8;  class=\"custom-color-blockqute-mark\">&#xe60c;<\/span><\/div><div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: -22px;\"><\/div>[vc_column_text]Lorem ipsum dolor sit amet, consectetur adi pisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis exercitation ullamco laboris nisiut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt.[\/vc_column_text]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 50px;\"><\/div>[\/vc_column][vc_column offset=&#8221;vc_col-md-6&#8243;]<div class=\"centered-box gem-image-centered-box\"><div class=\"gem-image gem-wrapbox gem-wrapbox-style-default gem-wrapbox-position-centered lazy-loading\"  style=\"\"><div class=\"gem-wrapbox-inner  lazy-loading-item\"  data-ll-effect=\"move-up\"><a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/2-7.jpg\" class=\"fancybox\"><img class=\"gem-wrapbox-element img-responsive\" src=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/2-7.jpg\" alt=\"\"\/><\/a><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1547452732428{margin-bottom: 0px !important;}&#8221;][vc_column]<div class=\"clearboth\"><\/div><div class=\"gem-divider \" style=\"margin-top: 30px;\"><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1547452732428{margin-bottom: 0px !important;}&#8221;][vc_column]<div class=\"preloader save-space\"><div class=\"preloader-spin\"><\/div><\/div><div class=\"gallery-preloader-wrapper\"> <div class=\"row\" style=\"margin-top: -21px\"> <div class=\"gem-gallery-grid col-lg-12 col-md-12 col-sm-12 gallery-style-justified hover-default loading-animation item-animation-move-up columns-4 gaps-margin \" data-hover=\"default\"> <ul style=\"margin-left: -21px; margin-right: -21px;\" class=\"gallery-set clearfix\" data-max-row-height=\"280\"> <li style=\"padding: 21px\" class=\"gallery-item col-lg-3 col-md-3 col-sm-4 col-xs-6 item-animations-not-inited post-826 post type-post status-publish format-standard has-post-thumbnail category-style-posts tag-beauty tag-events tag-fashion\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1100px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7-thegem-gallery-justified-4x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"3\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a03cb5e1d0ef\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/3-7.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-3 col-md-3 col-sm-4 col-xs-6 item-animations-not-inited post-826 post type-post status-publish format-standard has-post-thumbnail category-style-posts tag-beauty tag-events tag-fashion\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1100px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2-thegem-gallery-justified-4x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"6\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a03cb5e1d0ef\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/6-2.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-3 col-md-3 col-sm-4 col-xs-6 item-animations-not-inited post-826 post type-post status-publish format-standard has-post-thumbnail category-style-posts tag-beauty tag-events tag-fashion\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1100px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5-thegem-gallery-justified-4x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"5\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a03cb5e1d0ef\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/5-5.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <li style=\"padding: 21px\" class=\"gallery-item col-lg-3 col-md-3 col-sm-4 col-xs-6 item-animations-not-inited post-826 post type-post status-publish format-standard has-post-thumbnail category-style-posts tag-beauty tag-events tag-fashion\"> <div class=\"wrap gem-wrapbox-style-default\"> <div class=\"overlay-wrap\"> <div class=\"image-wrap \"> <picture> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7-thegem-gallery-justified-2x-500.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7-thegem-gallery-justified-3x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1100px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7-thegem-gallery-justified-4x.jpg 1x, https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7-thegem-gallery-justified.jpg 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7-thegem-gallery-justified.jpg\" width=\"660\" height=\"600\" class=\"attachment-thegem-gallery-justified\" alt=\"4\" \/> <\/picture> <\/div> <div class=\"overlay \"> <div class=\"overlay-circle\"><\/div> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7.jpg\" class=\"gallery-item-link fancy-gallery\" data-fancybox=\"gallery-6a03cb5e1d0ef\"> <span class=\"slide-info\"> <\/span> <\/a> <div class=\"overlay-content\"> <div class=\"overlay-content-center\"> <div class=\"overlay-content-inner\"> <a href=\"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-content\/uploads\/2017\/10\/4-7.jpg\" class=\"icon photo \" > <\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <\/li> <\/ul> <\/div> <\/div> <\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorem Ipsum. Proin gravida nibh vel velit auctor aliquet. Aenean sollicitudin, lorem quis bibendum auctor, nisi elit consequat ipsum.<\/p>\n","protected":false},"author":2,"featured_media":831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[5,6,4],"_links":{"self":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/posts\/826"}],"collection":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/comments?post=826"}],"version-history":[{"count":3,"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/posts\/826\/revisions"}],"predecessor-version":[{"id":1011,"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/posts\/826\/revisions\/1011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/media\/831"}],"wp:attachment":[{"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/media?parent=826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/categories?post=826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/codex-themes.com\/thegem\/sites\/beauty-salon\/wp-json\/wp\/v2\/tags?post=826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}